{"id":5250,"date":"2026-01-13T16:50:16","date_gmt":"2026-01-13T19:50:16","guid":{"rendered":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/?p=5250"},"modified":"2026-01-13T16:50:17","modified_gmt":"2026-01-13T19:50:17","slug":"operacion-pollux-22-allanamientos-y-16-detenidos-por-venta-de-drogas-en-la-ciudad-de-artigas","status":"publish","type":"post","link":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/2026\/01\/13\/operacion-pollux-22-allanamientos-y-16-detenidos-por-venta-de-drogas-en-la-ciudad-de-artigas\/","title":{"rendered":"Operaci\u00f3n Pollux: 22 allanamientos y 16 detenidos por venta de drogas en la ciudad de Artigas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Jefatura de Polic\u00eda de Artigas, a trav\u00e9s de la Direcci\u00f3n de Informaci\u00f3n T\u00e1ctica y la Brigada Departamental Antidrogas, llev\u00f3 adelante la denominada operaci\u00f3n Pollux, un amplio operativo orientado a desarticular una organizaci\u00f3n criminal de origen brasile\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n, iniciada en el mes de diciembre y dirigida por la Fiscal\u00eda de 1\u00b0 Turno, permiti\u00f3 identificar la presencia, en la ciudad de Artigas, de integrantes de la facci\u00f3n criminal Os Manos, quienes estar\u00edan intentando expandir su territorio de venta de sustancias estupefacientes en distintos barrios de la capital departamental, principalmente en Progreso, Cerro Ejido, Ayu\u00ed y Rampla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a las actuaciones, el grupo utilizaba la intimidaci\u00f3n y la violencia como principal m\u00e9todo de control territorial, adem\u00e1s de reclutar a personas menores de edad para la comercializaci\u00f3n de drogas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado del trabajo de an\u00e1lisis, levantamiento de informaci\u00f3n y tareas de campo, se lograron establecer v\u00ednculos entre los investigados y diversos puntos utilizados como acopio de sustancias il\u00edcitas, armas de fuego y otros elementos relacionados con la actividad delictiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elevadas las actuaciones ante la Fiscal\u00eda, se gestion\u00f3 21 \u00f3rdenes de allanamiento, 19 solicitudes de detenci\u00f3n, y una requisa y conducci\u00f3n desde la Unidad N.\u00ba 21 del Instituto Nacional de Rehabilitaci\u00f3n (INR). Para la ejecuci\u00f3n del operativo, se cont\u00f3 con el apoyo de la Direcci\u00f3n Nacional Guardia Republicana, as\u00ed como de las Jefaturas de Polic\u00eda de Salto, Rivera y Tacuaremb\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En total se realizaron 22 allanamientos simult\u00e1neos, que culminaron con la detenci\u00f3n de 16 personas, mientras que otras seis resultaron requeridas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el operativo se incaut\u00f3: 16 celulares, sustancias estupefacientes como coca\u00edna, marihuana y pasta base, m\u00e1s de 50.000 pesos uruguayos y reales, balanzas de precisi\u00f3n, una camioneta, una moto y 50 cartuchos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los detenidos fueron puestos a disposici\u00f3n de la Fiscal\u00eda de 1.\u00ba Turno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Jefatura de Polic\u00eda de Artigas, a trav\u00e9s de la Direcci\u00f3n de Informaci\u00f3n T\u00e1ctica y la Brigada Departamental Antidrogas, llev\u00f3 adelante la denominada operaci\u00f3n Pollux, un amplio operativo orientado a desarticular una organizaci\u00f3n criminal de origen brasile\u00f1o. La investigaci\u00f3n, iniciada en el mes de diciembre y dirigida por la Fiscal\u00eda de 1\u00b0 Turno, permiti\u00f3 identificar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5251,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[182],"tags":[4956,4955,355,354,1015,4954,2174],"class_list":["post-5250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucesos","tag-16-detenidos","tag-22-allanamientos","tag-artigas","tag-drogas","tag-operacion","tag-pollux","tag-venta"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts\/5250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/comments?post=5250"}],"version-history":[{"count":1,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts\/5250\/revisions"}],"predecessor-version":[{"id":5252,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts\/5250\/revisions\/5252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/media\/5251"}],"wp:attachment":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/media?parent=5250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/categories?post=5250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/tags?post=5250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}