{"id":4188,"date":"2025-11-24T12:39:01","date_gmt":"2025-11-24T15:39:01","guid":{"rendered":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/?p=4188"},"modified":"2025-11-24T12:39:01","modified_gmt":"2025-11-24T15:39:01","slug":"operativo-antidrogas-en-la-ciudad-de-dolores-culmina-con-cinco-formalizaciones-y-condenas","status":"publish","type":"post","link":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/2025\/11\/24\/operativo-antidrogas-en-la-ciudad-de-dolores-culmina-con-cinco-formalizaciones-y-condenas\/","title":{"rendered":"Operativo antidrogas en la ciudad de Dolores culmina con cinco formalizaciones y condenas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un operativo de la Brigada Departamental Antidrogas ejecutado en la ciudad de Dolores permiti\u00f3 detener a cinco personas investigadas por actividades vinculadas al suministro de estupefacientes. En los allanamientos se incautaron diversas sustancias prohibidas, dinero en moneda nacional y extranjera, tel\u00e9fonos celulares y otros elementos relevantes. Tras la instancia judicial, todos los detenidos resultaron formalizados y condenados por distintos delitos.<br>En el marco de la Operaci\u00f3n Vestigio, y en cumplimiento de directivas fiscales relacionadas con la investigaci\u00f3n de puntos de venta de estupefacientes en la ciudad de Dolores, la Brigada Departamental Antidrogas llev\u00f3 adelante un despliegue operativo destinado a intervenir varios inmuebles vinculados a dicha actividad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esa l\u00ednea, se realizaron cinco allanamientos en simult\u00e1neo, contando con el apoyo de distintas unidades policiales. Como resultado del procedimiento, se detuvo a cinco personas y se incaut\u00f3 una importante cantidad de objetos asociados a la investigaci\u00f3n, entre ellos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>$ 348.095 (pesos uruguayos)<\/li>\n\n\n\n<li>U$S 2.915 (d\u00f3lares estadounidenses)<\/li>\n\n\n\n<li>9 tel\u00e9fonos celulares<\/li>\n\n\n\n<li>1 cartucho calibre 38<\/li>\n\n\n\n<li>1 balanza de precisi\u00f3n<\/li>\n\n\n\n<li>Sustancia vegetal s\u00edmil marihuana (18,3 g)<\/li>\n\n\n\n<li>Sustancia en piedra s\u00edmil pasta base (42,8 g)<\/li>\n\n\n\n<li>Tres piedras adicionales s\u00edmil pasta base<\/li>\n\n\n\n<li>Sustancia en polvo color blanco s\u00edmil coca\u00edna (4,3 g)<\/li>\n\n\n\n<li>Una moto Baccio PX110<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La Fiscal del caso dispuso la detenci\u00f3n de las personas involucradas, la incautaci\u00f3n de los objetos y la continuidad de las actuaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez finalizada la audiencia en sede del Juzgado Letrado de Dolores de 2.\u00ba Turno, se dispuso lo siguiente:<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Formalizaci\u00f3n y condena<\/h5>\n\n\n\n<ul class=\"wp-block-list\">\n<li>J.C.S.S.(32), como autor penalmente responsable de un\u00a0<em>delito continuado previsto en el art\u00edculo 34 de la Ley 14.294 en la modalidad de suministro oneroso de sustancia estupefaciente<\/em>, fue condenado a 2 a\u00f1os y 10 meses de penitenciar\u00eda.<\/li>\n\n\n\n<li>R.R.S.S.(31), como autora penalmente responsable de un\u00a0<em>delito continuado previsto en el art\u00edculo 34 de la Ley 14.294 en la modalidad de suministro oneroso de sustancia estupefaciente<\/em>, fue condenada a 2 a\u00f1os y 6 meses de penitenciar\u00eda.<\/li>\n\n\n\n<li>Carla Deborah Andriolo Espindola (38), como autora penalmente responsable de un\u00a0<em>delito de encubrimiento agravado<\/em>, fue condenada a 6 meses de penitenciar\u00eda.<\/li>\n\n\n\n<li>Brian Alejandro Helguera Alvarez (25)., como autor penalmente responsable de\u00a0<em>dos delitos de hurto especialmente agravado en reiteraci\u00f3n real con un delito continuado previsto en el art\u00edculo 34 de la Ley 14.294 en la modalidad de suministro oneroso de sustancias estupefacientes<\/em>, fue condenado a 2 a\u00f1os y 6 meses de penitenciar\u00eda.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp; &nbsp; &nbsp; &nbsp;Los otros delitos de hurto por los que fue formalizado ocurrieron el d\u00eda 24\/10\/2025 en calle Treinta y Tres y Misiones, el d\u00eda 13\/11\/2025, hurto a comercio en calle Dr Pastor Sotura y Veinticinco de Mayo y hurto en finca ocurrido el 14\/11\/2025.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jos\u00e9 Maria Mendez Freitas (29), como autor penalmente responsable de un\u00a0<em>delito de hurto especialmente agravado<\/em>, fue condenado a 18 meses de penitenciar\u00eda.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp; &nbsp; &nbsp; &nbsp;Esto de acuerdo a hurto ocurrido el d\u00eda 24\/10\/2025 en calle Treinta y Tres y Misiones<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se dispuso el decomiso total del dinero incautado, de los celulares, del veh\u00edculo, y de todas las sustancias, por tratarse de instrumentos y efectos del delito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un operativo de la Brigada Departamental Antidrogas ejecutado en la ciudad de Dolores permiti\u00f3 detener a cinco personas investigadas por actividades vinculadas al suministro de estupefacientes. En los allanamientos se incautaron diversas sustancias prohibidas, dinero en moneda nacional y extranjera, tel\u00e9fonos celulares y otros elementos relevantes. Tras la instancia judicial, todos los detenidos resultaron formalizados [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4189,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[182],"tags":[634,1869,1520,354,4216,504,316,4217],"class_list":["post-4188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucesos","tag-antidrogas","tag-brigada","tag-dolores","tag-drogas","tag-formalizaciones","tag-operativo","tag-soriano","tag-y-condenas"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts\/4188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/comments?post=4188"}],"version-history":[{"count":1,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts\/4188\/revisions"}],"predecessor-version":[{"id":4190,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts\/4188\/revisions\/4190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/media\/4189"}],"wp:attachment":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/media?parent=4188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/categories?post=4188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/tags?post=4188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}