{"id":2126,"date":"2025-08-19T17:15:44","date_gmt":"2025-08-19T20:15:44","guid":{"rendered":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/?p=2126"},"modified":"2025-08-19T17:15:44","modified_gmt":"2025-08-19T20:15:44","slug":"uruguay-camino-a-valencia","status":"publish","type":"post","link":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/2025\/08\/19\/uruguay-camino-a-valencia\/","title":{"rendered":"Uruguay \u201cCamino a Valencia\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco del D\u00eda Internacional de la Paella celebrado el 20 de setiembre en Valencia, se realizar\u00e1 el 7mo Campeonato Mundial de Paella, en donde Uruguay estar\u00e1 representado por el Campe\u00f3n Nacional, Ian Escobar y lo acompa\u00f1ar\u00e1 Javier Pi\u00f1eiro finalista del Mundial en 2021.<br>El Ministro de Turismo Pablo Menoni destac\u00f3 la importancia de la participaci\u00f3n de Uruguay en este campeonato mundial, \u201ceste tipo de participaciones hace conocer m\u00e1s a Uruguay y sus destinos, no solo van a mostrar los diferentes sabores, sino tambi\u00e9n esa historia que transmiten al cocina. Desde nuestro lugar seguiremos apoyando estas instancias para fortalecer el productos gastron\u00f3mico y ayudar a consolidar este tipo de competencias\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte el Director de Turismo de Maldonado Edgar Silveira indic\u00f3, \u201cEl Campeonato Nacional de Paella va a continuar. Tenemos que seguir mejorando, apoyando y tenemos que seguir superando el nivel y sin duda teniendo el pr\u00f3ximo premio al Campeonato Mundial. Este tipo de eventos son importantes importante y para Uruguay entero la la confirmaci\u00f3n de que la gastronom\u00eda tambi\u00e9n es un veh\u00edculo para contar qui\u00e9nes somos, para generar nuevas oportunidades y para abrir las puertas en el mundo\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Campe\u00f3n Nacional de Paella 2024 Ian Escobar destac\u00f3 c\u00f3mo vivi\u00f3 el proceso del campeonato, \u201cencontr\u00e9 en Piri\u00e1polis una familia, una familia que trabaja por un fin com\u00fan que es el turismo, poner en valor los productos locales y los eventos que se hacen ah\u00ed\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde Valencia particip\u00f3 Miguel \u00c1ngel Castro el Director del World Paella Day, en donde remarc\u00f3 \u201cUruguay y Piri\u00e1polis han logrado un hito en este proceso, han sido los primeros en aprobar la clasificatoria para este campeonato mundial m\u00e1s prestigioso de este plato. Los participantes van a poder conocer Valencia y diferentes puntos destacados de la gastronom\u00eda\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de finalizada la conferencia se realiz\u00f3 una degustaci\u00f3n de paella cocinada en vivo para todos los que acompa\u00f1aron.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del D\u00eda Internacional de la Paella celebrado el 20 de setiembre en Valencia, se realizar\u00e1 el 7mo Campeonato Mundial de Paella, en donde Uruguay estar\u00e1 representado por el Campe\u00f3n Nacional, Ian Escobar y lo acompa\u00f1ar\u00e1 Javier Pi\u00f1eiro finalista del Mundial en 2021.El Ministro de Turismo Pablo Menoni destac\u00f3 la importancia de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[2,304],"tags":[804,1946,1945,217,242,1944],"class_list":["post-2126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","category-turismo","tag-campeonato","tag-menoni","tag-paella","tag-turismo","tag-uruguay","tag-valencia"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts\/2126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/comments?post=2126"}],"version-history":[{"count":1,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts\/2126\/revisions"}],"predecessor-version":[{"id":2128,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/posts\/2126\/revisions\/2128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/media\/2127"}],"wp:attachment":[{"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/media?parent=2126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/categories?post=2126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tododeporteynoticiasuruguay.com.uy\/new\/wp-json\/wp\/v2\/tags?post=2126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}